{"id":1212,"date":"2007-07-03T22:51:37","date_gmt":"2007-07-03T20:51:37","guid":{"rendered":"http:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/"},"modified":"2007-07-03T22:51:37","modified_gmt":"2007-07-03T20:51:37","slug":"kim-jestescie-tlumy-przybyszow","status":"publish","type":"post","link":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/","title":{"rendered":"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ?"},"content":{"rendered":"<p align=\"justify\">Dzi\u015b na blogu by\u0142o ponad 800 wej\u015b\u0107. Wczoraj ponad 700. A przedwczoraj ledwo 15. O co chodzi? Czy kto\u015b to potrafi wyt\u0142umaczy\u0107? Kim jeste\u015bcie nieznani? Czy to znowu jakis \u017cart z kategorii 'Mamy ci\u0119&#8217;?<\/p>\n<p align=\"justify\">Pr\u00f3buj\u0119 to zrozumie\u0107 &#8211; mo\u017ce tylko statystyka si\u0119 r\u0105bn\u0119\u0142a o jedno lub dwa zera? Czy to mo\u017cliwe?<\/p>\n<p align=\"justify\">\u00a0<\/p>\n<div style=\"text-align: center\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/skyisnotthelimit.eu\/wp-content\/uploads\/2020\/08\/reduce_speed_250x250.jpg?resize=250%2C180\" alt=\"\" width=\"250\" height=\"180\" \/><\/div>\n<p align=\"justify\">A mo\u017ce wpis o mandacie, kt\u00f3ry chyba nadawa\u0142by si\u0119 nawet do rubryki kryminalnej w jakim\u015b brukowcu wp\u0142yn\u0105\u0142 na masowo\u015b\u0107 jednostek czytelniczych?<\/p>\n<p align=\"justify\">Dziwnie si\u0119 z tym czuj\u0119, czy powinienem?<\/p>\n","protected":false},"excerpt":{"rendered":"<p align=\"justify\">Dzi\u015b &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-1212","post","type-post","status-publish","format-standard","hentry","category-poczatki-na-emigracji-i-nie-tylko"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ? - Sky Is Not The Limit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ? - Sky Is Not The Limit\" \/>\n<meta property=\"og:description\" content=\"Dzi\u015b ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/\" \/>\n<meta property=\"og:site_name\" content=\"Sky Is Not The Limit\" \/>\n<meta property=\"article:published_time\" content=\"2007-07-03T20:51:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/skyisnotthelimit.eu\/wp-content\/uploads\/2020\/08\/reduce_speed_250x250.jpg\" \/>\n<meta name=\"author\" content=\"wheyman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"wheyman\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/\"},\"author\":{\"name\":\"wheyman\",\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/#\\\/schema\\\/person\\\/78f7851d005fe410e699b55895b7b5f4\"},\"headline\":\"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ?\",\"datePublished\":\"2007-07-03T20:51:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/\"},\"wordCount\":95,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/#\\\/schema\\\/person\\\/78f7851d005fe410e699b55895b7b5f4\"},\"image\":{\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/skyisnotthelimit.eu\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/reduce_speed_250x250.jpg\",\"articleSection\":[\"Pocz\u0105tki na emigracji i nie tylko\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/\",\"url\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/\",\"name\":\"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ? - Sky Is Not The Limit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/skyisnotthelimit.eu\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/reduce_speed_250x250.jpg\",\"datePublished\":\"2007-07-03T20:51:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/#primaryimage\",\"url\":\"http:\\\/\\\/skyisnotthelimit.eu\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/reduce_speed_250x250.jpg\",\"contentUrl\":\"http:\\\/\\\/skyisnotthelimit.eu\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/reduce_speed_250x250.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/index.php\\\/2007\\\/07\\\/03\\\/kim-jestescie-tlumy-przybyszow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/#website\",\"url\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/\",\"name\":\"Sky Is Not The Limit\",\"description\":\"Spe\u0142nianie marze\u0144, wielka przygoda i odrobina szale\u0144stwa. Podr\u00f3\u017ce i \u017cycie codzienne na egzotycznej emigracji w Katarze.\",\"publisher\":{\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/#\\\/schema\\\/person\\\/78f7851d005fe410e699b55895b7b5f4\"},\"alternateName\":\"blog wheyman qatar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/skyisnotthelimit.eu\\\/#\\\/schema\\\/person\\\/78f7851d005fe410e699b55895b7b5f4\",\"name\":\"wheyman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf223156036c08df8bd072e48d77246f6ea4d1718097aeb645be3e853649705b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf223156036c08df8bd072e48d77246f6ea4d1718097aeb645be3e853649705b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf223156036c08df8bd072e48d77246f6ea4d1718097aeb645be3e853649705b?s=96&d=mm&r=g\",\"caption\":\"wheyman\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf223156036c08df8bd072e48d77246f6ea4d1718097aeb645be3e853649705b?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/skyisnotthelimit.eu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ? - Sky Is Not The Limit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/","og_locale":"pl_PL","og_type":"article","og_title":"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ? - Sky Is Not The Limit","og_description":"Dzi\u015b ...","og_url":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/","og_site_name":"Sky Is Not The Limit","article_published_time":"2007-07-03T20:51:37+00:00","og_image":[{"url":"http:\/\/skyisnotthelimit.eu\/wp-content\/uploads\/2020\/08\/reduce_speed_250x250.jpg","type":"","width":"","height":""}],"author":"wheyman","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"wheyman"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/#article","isPartOf":{"@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/"},"author":{"name":"wheyman","@id":"https:\/\/skyisnotthelimit.eu\/#\/schema\/person\/78f7851d005fe410e699b55895b7b5f4"},"headline":"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ?","datePublished":"2007-07-03T20:51:37+00:00","mainEntityOfPage":{"@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/"},"wordCount":95,"commentCount":0,"publisher":{"@id":"https:\/\/skyisnotthelimit.eu\/#\/schema\/person\/78f7851d005fe410e699b55895b7b5f4"},"image":{"@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/#primaryimage"},"thumbnailUrl":"http:\/\/skyisnotthelimit.eu\/wp-content\/uploads\/2020\/08\/reduce_speed_250x250.jpg","articleSection":["Pocz\u0105tki na emigracji i nie tylko"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/","url":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/","name":"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ? - Sky Is Not The Limit","isPartOf":{"@id":"https:\/\/skyisnotthelimit.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/#primaryimage"},"image":{"@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/#primaryimage"},"thumbnailUrl":"http:\/\/skyisnotthelimit.eu\/wp-content\/uploads\/2020\/08\/reduce_speed_250x250.jpg","datePublished":"2007-07-03T20:51:37+00:00","breadcrumb":{"@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/#primaryimage","url":"http:\/\/skyisnotthelimit.eu\/wp-content\/uploads\/2020\/08\/reduce_speed_250x250.jpg","contentUrl":"http:\/\/skyisnotthelimit.eu\/wp-content\/uploads\/2020\/08\/reduce_speed_250x250.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/skyisnotthelimit.eu\/index.php\/2007\/07\/03\/kim-jestescie-tlumy-przybyszow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyisnotthelimit.eu\/"},{"@type":"ListItem","position":2,"name":"Kim jeste\u015bcie, t\u0142umy przybysz\u00f3w ?"}]},{"@type":"WebSite","@id":"https:\/\/skyisnotthelimit.eu\/#website","url":"https:\/\/skyisnotthelimit.eu\/","name":"Sky Is Not The Limit","description":"Spe\u0142nianie marze\u0144, wielka przygoda i odrobina szale\u0144stwa. Podr\u00f3\u017ce i \u017cycie codzienne na egzotycznej emigracji w Katarze.","publisher":{"@id":"https:\/\/skyisnotthelimit.eu\/#\/schema\/person\/78f7851d005fe410e699b55895b7b5f4"},"alternateName":"blog wheyman qatar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyisnotthelimit.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":["Person","Organization"],"@id":"https:\/\/skyisnotthelimit.eu\/#\/schema\/person\/78f7851d005fe410e699b55895b7b5f4","name":"wheyman","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/secure.gravatar.com\/avatar\/bf223156036c08df8bd072e48d77246f6ea4d1718097aeb645be3e853649705b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf223156036c08df8bd072e48d77246f6ea4d1718097aeb645be3e853649705b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf223156036c08df8bd072e48d77246f6ea4d1718097aeb645be3e853649705b?s=96&d=mm&r=g","caption":"wheyman"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/bf223156036c08df8bd072e48d77246f6ea4d1718097aeb645be3e853649705b?s=96&d=mm&r=g"},"sameAs":["https:\/\/skyisnotthelimit.eu"]}]}},"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"ultp_layout_landscape_large":false,"ultp_layout_landscape":false,"ultp_layout_portrait":false,"ultp_layout_square":false,"twentyseventeen-featured-image":false,"twentyseventeen-thumbnail-avatar":false},"uagb_author_info":{"display_name":"wheyman","author_link":"https:\/\/skyisnotthelimit.eu\/index.php\/author\/majki1234\/"},"uagb_comment_info":1,"uagb_excerpt":"Dzi\u015b ...","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/skyisnotthelimit.eu\/index.php\/wp-json\/wp\/v2\/posts\/1212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyisnotthelimit.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skyisnotthelimit.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skyisnotthelimit.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/skyisnotthelimit.eu\/index.php\/wp-json\/wp\/v2\/comments?post=1212"}],"version-history":[{"count":0,"href":"https:\/\/skyisnotthelimit.eu\/index.php\/wp-json\/wp\/v2\/posts\/1212\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyisnotthelimit.eu\/index.php\/wp-json\/wp\/v2\/media?parent=1212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skyisnotthelimit.eu\/index.php\/wp-json\/wp\/v2\/categories?post=1212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skyisnotthelimit.eu\/index.php\/wp-json\/wp\/v2\/tags?post=1212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}